{"id":821,"date":"2026-03-29T10:39:30","date_gmt":"2026-03-29T08:39:30","guid":{"rendered":"https:\/\/f6kop.com\/?p=821"},"modified":"2026-03-29T10:40:17","modified_gmt":"2026-03-29T08:40:17","slug":"nous-sommes-231-a-avoir-accorde-notre-confiance-a-f6kop","status":"publish","type":"post","link":"https:\/\/f6kop.com\/index.php\/2026\/03\/29\/nous-sommes-231-a-avoir-accorde-notre-confiance-a-f6kop\/","title":{"rendered":"nous sommes 231 \u00e0 avoir accord\u00e9 notre confiance \u00e0 F6KOP"},"content":{"rendered":"\n<p>Super les KOPains<\/p>\n\n\n\n<p>Ce matin, nous sommes 231 \u00e0 avoir accord\u00e9 notre confiance \u00e0 F6KOP.<br>231 KOPains et KOPines anim\u00e9s par une m\u00eame envie : aller toujours plus loin.<\/p>\n\n\n\n<p>Envie d\u2019innover, d\u2019oser, d\u2019essayer de faire ce que d\u2019autres ne font pas\u2026<br>Toujours avec ce petit suppl\u00e9ment d\u2019\u00e2me qui fait toute la diff\u00e9rence.<\/p>\n\n\n\n<p>Merci \u00e0 toutes et \u00e0 tous, \u00e0 toutes les forces vives de F6KOP.<br>Vous \u00eates l\u2019\u00e9nergie, le moteur, la passion qui font vivre pleinement votre club.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/f6kop.com\/wp-content\/uploads\/2026\/03\/635b5810-c77c-4cff-a5e3-a09ef24cfa92-683x1024.png\" alt=\"\" class=\"wp-image-823\" srcset=\"https:\/\/f6kop.com\/wp-content\/uploads\/2026\/03\/635b5810-c77c-4cff-a5e3-a09ef24cfa92-683x1024.png 683w, https:\/\/f6kop.com\/wp-content\/uploads\/2026\/03\/635b5810-c77c-4cff-a5e3-a09ef24cfa92-200x300.png 200w, https:\/\/f6kop.com\/wp-content\/uploads\/2026\/03\/635b5810-c77c-4cff-a5e3-a09ef24cfa92-768x1152.png 768w, https:\/\/f6kop.com\/wp-content\/uploads\/2026\/03\/635b5810-c77c-4cff-a5e3-a09ef24cfa92.png 1024w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Super les KOPains Ce matin, nous sommes 231 \u00e0 avoir accord\u00e9 notre confiance \u00e0 F6KOP.231 KOPains et KOPines anim\u00e9s par une m\u00eame envie : aller toujours plus loin. Envie d\u2019innover, d\u2019oser, d\u2019essayer de faire ce que d\u2019autres ne font pas\u2026Toujours avec ce petit suppl\u00e9ment d\u2019\u00e2me qui fait toute la diff\u00e9rence. Merci \u00e0 toutes et \u00e0 tous, \u00e0 toutes les forces vives de F6KOP.Vous \u00eates l\u2019\u00e9nergie, le moteur, la passion qui font vivre pleinement votre club.<\/p>\n","protected":false},"author":3,"featured_media":823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11],"tags":[],"class_list":["post-821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveau-membre","category-vie-du-club"],"_links":{"self":[{"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/posts\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":1,"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/posts\/821\/revisions"}],"predecessor-version":[{"id":824,"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/posts\/821\/revisions\/824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/media\/823"}],"wp:attachment":[{"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/media?parent=821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/categories?post=821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/f6kop.com\/index.php\/wp-json\/wp\/v2\/tags?post=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}